{"id":427084,"date":"2026-09-02T13:22:37","date_gmt":"2026-09-02T17:22:37","guid":{"rendered":"https:\/\/www.eldiario.net\/portal\/?p=427084"},"modified":"2026-09-02T13:22:37","modified_gmt":"2026-09-02T17:22:37","slug":"heridas-8-personas-tras-un-ataque-ruso-en-odesa","status":"publish","type":"post","link":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/","title":{"rendered":"Heridas 8 personas tras un ataque ruso en Odesa"},"content":{"rendered":"<p>Un nuevo ataque de Rusia con drones y misiles contra la regi\u00f3n de Odesa calificado de \u00abmasivo\u00bb por las autoridades provoc\u00f3 este mi\u00e9rcoles da\u00f1os en equipamiento energ\u00e9tico y dej\u00f3 sin suministro el\u00e9ctrico a una parte de la poblaci\u00f3n de la zona, seg\u00fan informaron el Ministerio de Energ\u00eda de Ucrania y la compa\u00f1\u00eda el\u00e9ctrica p\u00fablica, Ukrenergo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo ataque de Rusia con drones y misiles contra la regi\u00f3n de Odesa calificado de \u00abmasivo\u00bb por las autoridades provoc\u00f3 este mi\u00e9rcoles da\u00f1os en equipamiento energ\u00e9tico y dej\u00f3 sin suministro el\u00e9ctrico a una parte de la poblaci\u00f3n de la zona, seg\u00fan informaron el Ministerio de Energ\u00eda de Ucrania y la compa\u00f1\u00eda el\u00e9ctrica p\u00fablica, Ukrenergo.<\/p>\n","protected":false},"author":7,"featured_media":427085,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-427084","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ultima-hora"],"acf":{"antetitulo":"Ucrania"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia\" \/>\n<meta property=\"og:description\" content=\"Un nuevo ataque de Rusia con drones y misiles contra la regi\u00f3n de Odesa calificado de \u00abmasivo\u00bb por las autoridades provoc\u00f3 este mi\u00e9rcoles da\u00f1os en equipamiento energ\u00e9tico y dej\u00f3 sin suministro el\u00e9ctrico a una parte de la poblaci\u00f3n de la zona, seg\u00fan informaron el Ministerio de Energ\u00eda de Ucrania y la compa\u00f1\u00eda el\u00e9ctrica p\u00fablica, Ukrenergo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario - Bolivia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eldiario.bolivia\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T17:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Viviana Monrroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:site\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viviana Monrroy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/\"},\"author\":{\"name\":\"Viviana Monrroy\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/ba370d92d160f4d3574381f6d9b78fab\"},\"headline\":\"Heridas 8 personas tras un ataque ruso en Odesa\",\"datePublished\":\"2026-09-02T17:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/\"},\"wordCount\":74,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/adelantos-8-copia-1.webp\",\"articleSection\":[\"\u00daltima Hora\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/\",\"name\":\"Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/adelantos-8-copia-1.webp\",\"datePublished\":\"2026-09-02T17:22:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/adelantos-8-copia-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/adelantos-8-copia-1.webp\",\"width\":506,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2026\\\/09\\\/02\\\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heridas 8 personas tras un ataque ruso en Odesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"name\":\"El Diario - Decano de la prensa nacional\",\"description\":\"El Diario - Decano de la prensa nacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\",\"name\":\"El Diario - Decano de la prensa nacional\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"width\":272,\"height\":52,\"caption\":\"El Diario - Decano de la prensa nacional\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eldiario.bolivia\\\/\",\"https:\\\/\\\/x.com\\\/eldiario_net\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/ba370d92d160f4d3574381f6d9b78fab\",\"name\":\"Viviana Monrroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g\",\"caption\":\"Viviana Monrroy\"},\"sameAs\":[\"http:\\\/\\\/www.eldiario.net\"],\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/author\\\/vivianamonrroy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/","og_locale":"es_ES","og_type":"article","og_title":"Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia","og_description":"Un nuevo ataque de Rusia con drones y misiles contra la regi\u00f3n de Odesa calificado de \u00abmasivo\u00bb por las autoridades provoc\u00f3 este mi\u00e9rcoles da\u00f1os en equipamiento energ\u00e9tico y dej\u00f3 sin suministro el\u00e9ctrico a una parte de la poblaci\u00f3n de la zona, seg\u00fan informaron el Ministerio de Energ\u00eda de Ucrania y la compa\u00f1\u00eda el\u00e9ctrica p\u00fablica, Ukrenergo.","og_url":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/","og_site_name":"El Diario - Bolivia","article_publisher":"https:\/\/www.facebook.com\/eldiario.bolivia\/","article_published_time":"2026-09-02T17:22:37+00:00","og_image":[{"width":506,"height":506,"url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp","type":"image\/webp"}],"author":"Viviana Monrroy","twitter_card":"summary_large_image","twitter_creator":"@eldiario_net","twitter_site":"@eldiario_net","twitter_misc":{"Escrito por":"Viviana Monrroy","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#article","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/"},"author":{"name":"Viviana Monrroy","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/ba370d92d160f4d3574381f6d9b78fab"},"headline":"Heridas 8 personas tras un ataque ruso en Odesa","datePublished":"2026-09-02T17:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/"},"wordCount":74,"publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp","articleSection":["\u00daltima Hora"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/","url":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/","name":"Heridas 8 personas tras un ataque ruso en Odesa - El Diario - Bolivia","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp","datePublished":"2026-09-02T17:22:37+00:00","breadcrumb":{"@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#primaryimage","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2026\/09\/adelantos-8-copia-1.webp","width":506,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiario.net\/portal\/2026\/09\/02\/heridas-8-personas-tras-un-ataque-ruso-en-odesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiario.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Heridas 8 personas tras un ataque ruso en Odesa"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiario.net\/portal\/#website","url":"https:\/\/www.eldiario.net\/portal\/","name":"El Diario - Decano de la prensa nacional","description":"El Diario - Decano de la prensa nacional","publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiario.net\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiario.net\/portal\/#organization","name":"El Diario - Decano de la prensa nacional","url":"https:\/\/www.eldiario.net\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","width":272,"height":52,"caption":"El Diario - Decano de la prensa nacional"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eldiario.bolivia\/","https:\/\/x.com\/eldiario_net"]},{"@type":"Person","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/ba370d92d160f4d3574381f6d9b78fab","name":"Viviana Monrroy","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfd1611ed5600959a0e5a9754503b6c05d1dcf190010998e0363aee2ad98afca?s=96&d=mm&r=g","caption":"Viviana Monrroy"},"sameAs":["http:\/\/www.eldiario.net"],"url":"https:\/\/www.eldiario.net\/portal\/author\/vivianamonrroy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/427084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/comments?post=427084"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/427084\/revisions"}],"predecessor-version":[{"id":427086,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/427084\/revisions\/427086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media\/427085"}],"wp:attachment":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media?parent=427084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/categories?post=427084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/tags?post=427084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}