{"id":307265,"date":"2025-06-04T06:04:20","date_gmt":"2025-06-04T10:04:20","guid":{"rendered":"https:\/\/www.eldiario.net\/portal\/?p=307265"},"modified":"2025-06-04T06:04:20","modified_gmt":"2025-06-04T10:04:20","slug":"horoscopo-semanal-145","status":"publish","type":"post","link":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/","title":{"rendered":"Hor\u00f3scopo semanal"},"content":{"rendered":"<p><strong><em>Nota a los lectores: <\/em><\/strong><em>Betty B. Mercado, sobrina y colaboradora del fallecido astr\u00f3logo Walter Mercado, contin\u00faa su legado escribiendo el hor\u00f3scopo del d\u00eda.<\/em><\/p>\n<p><strong>Aries<\/strong><\/p>\n<p><strong>(20 de marzo &#8211; 18 de abril)<\/strong><\/p>\n<p>Estar\u00e1s ahora muy convincente y directo al comunicarte. Tu energ\u00eda se exalta y querr\u00e1s hacer mucho en poco tiempo. Esto traer\u00e1 por consecuencia diferencias y tensiones entre aquellos que no van a tu velocidad. S\u00e9 considerado y mot\u00edvalos a que trabajen contigo aun cuando tengas que disminuir tu tan acelerado paso. N\u00fameros de suerte: 19, 37, 39.<\/p>\n<p><strong>Tauro<\/strong><\/p>\n<p><strong>(19 de abril &#8211; 19 de mayo)<\/strong><\/p>\n<p>Estar\u00e1s en las de dar tu opini\u00f3n en todo y esto podr\u00eda meterte en problemas, envolvi\u00e9ndote en situaciones algo serias. Ten bien presente que no tienes que alzar la voz para que te escuchen. Respeta las ideas de otros para que respeten las tuyas. Ellos tienen derecho y puede que aprendas algo tambi\u00e9n. Ejercita tu mente, lee y asiste a todo lo que estimule tu intelecto y aumente tu sabidur\u00eda. N\u00fameros de suerte: 47, 15, 4.<\/p>\n<p><strong>G\u00e9minis<\/strong><\/p>\n<p><strong>(20 de mayo &#8211; 19 de junio)<\/strong><\/p>\n<p>Si sientes que necesitas tomarte unas vacaciones ahora es el momento de darle forma a esos planes. Lo relacionado con el extranjero tanto de lugares como de personas est\u00e1 bien aspectado ahora. La energ\u00eda planetaria te impulsa a divertirte y a expandir tus horizontes, especialmente con aquellos que amas. N\u00fameros de suerte: 41, 25, 12.<\/p>\n<p><strong>C\u00e1ncer<\/strong><\/p>\n<p><strong>(20 de junio &#8211; 21 de julio)<\/strong><\/p>\n<p>Aunque tu situaci\u00f3n econ\u00f3mica se encuentre bajo control, no debes excederte en ning\u00fan tipo de gasto. Utiliza con cautela y sensatez lo que tienes ahorrado hasta el momento. No te dejes llevar por los impulsos ya que aquello que lleves a cabo a la ligera te lleva a tomar decisiones que m\u00e1s tarde podr\u00edas lamentar, C\u00e1ncer. N\u00fameros de suerte: 21, 8, 2.<\/p>\n<p><strong>Leo<\/strong><\/p>\n<p><strong>(22 de julio &#8211; 21 de agosto)<\/strong><\/p>\n<p>Es tiempo ya de enfrentar un problema que ven\u00edas evadiendo por alg\u00fan tiempo ya que aquello que evitas si no lo enfrentas, crecer\u00e1 en proporci\u00f3n. Es mejor sentarse y poner las cartas sobre la mesa y deshacerse de todo lo turbio, de lo oculto. Te sentir\u00e1s m\u00e1s aliviado emocionalmente. Estar\u00e1s m\u00e1s maduro y realista en tus relaciones de amor. N\u00fameros de suerte: 25, 3, 14.<\/p>\n<p><strong>Virgo<\/strong><\/p>\n<p><strong>(22 de agosto &#8211; 21 de sept.)<\/strong><\/p>\n<p>No busques excusas para no enfrentar y resolver tus problemas. Organiza tus pensamientos y b\u00fascale soluci\u00f3n. Pon en orden de prioridad aquello que tienes que hacer de acuerdo con su urgencia o necesidad. No te sientes a lamentarte. Act\u00faa, mu\u00e9vete y ver\u00e1s de lo que eres capaz cuando te lo propones. N\u00fameros de suerte: 16, 2, 14.<\/p>\n<p><strong>Libra<\/strong><\/p>\n<p><strong>(22 de sept. &#8211;<\/strong><strong> 22 de oct.)<\/strong><\/p>\n<p>El \u00e9xito ser\u00e1 tuyo si sabes c\u00f3mo adaptarte a todos estos cambios que se est\u00e1n manifestando en tu vida tan apresuradamente. Todo cambia de rumbo de un d\u00eda para otro, pero no te preocupes, tus energ\u00edas y tu sabidur\u00eda junto a tu encanto personal podr\u00e1 con todo esto y m\u00e1s. Escucha lo que te dice tu cuerpo, no te excedas al comer o beber. N\u00fameros de suerte: 3, 5, 22.<\/p>\n<p><strong>Escorpio<\/strong><\/p>\n<p><strong>(23 de oct. &#8211; 20 de nov.)<\/strong><\/p>\n<p>Espera mucha actividad en tu diario vivir. No tienes que decir que si, o aceptar todo lo que te digan o te propongan hacer. S\u00e9 m\u00e1s selectivo en cuanto a tus amistades. No desperdicies tus energ\u00edas en cosas o actividades que te quiten tu tiempo valioso y te agoten. No permitas que las preocupaciones afecten tu estado de \u00e1nimo. N\u00fameros de suerte: 4, 36, 20.<\/p>\n<p><strong>Sagitario<\/strong><\/p>\n<p><strong>(21 de nov. &#8211;<\/strong><strong> 20 de dic.)<\/strong><\/p>\n<p>Es hora de tomar las relaciones familiares en serio y sacar tiempo para tu familia y amigos. Toda actividad creativa est\u00e1 bien aspectada. Disfrutar\u00e1s de juegos o de visitar sitios como museos, teatros, galer\u00edas de arte, etc. Las relaciones en el amor mejorar\u00e1n notablemente si te muestras m\u00e1s flexible y cooperador para con ser amado. N\u00fameros de suerte: 8, 45, 12.<\/p>\n<p><strong>Capricornio<\/strong><\/p>\n<p><strong>(21 de dic. &#8211;<\/strong><strong> 18 de ene.)<\/strong><\/p>\n<p>Aunque t\u00fa eres un signo de car\u00e1cter pasivo, ahora estar\u00e1s en las de discutir sobre asuntos relacionados con temas de religi\u00f3n, filosof\u00eda o pol\u00edtica. Tu habilidad para llegar directamente a los dem\u00e1s exponiendo tus ideas se enfatiza, lo que te ayudar\u00e1 en toda labor caritativa en las que desees envolverte ahora. Tendr\u00e1s mucha energ\u00eda f\u00edsica. N\u00fameros de suerte: 21, 8, 7.<\/p>\n<p><strong>Acuario<\/strong><\/p>\n<p><strong>(19 de ene. &#8211; 17 de feb.)<\/strong><\/p>\n<p>Ponte al d\u00eda en tu trabajo y obligaciones para que luego te sobre tiempo y puedas disfrutar de tus pasatiempos favoritos. Cu\u00eddate de estar con personas que no se encuentran en buen estado de salud. Evita exponerte a situaciones peligrosas. No te quedes con rencores o calles algo que te moleste, esto puede afectar tambi\u00e9n tu salud. N\u00fameros de suerte: 6, 15, 30.<\/p>\n<p><strong>Piscis<\/strong><\/p>\n<p><strong>(18 de feb. &#8211; 19 de marzo)<\/strong><\/p>\n<p>A trav\u00e9s de conversaciones y negociaciones conocer\u00e1s a una persona que dejar\u00e1 una huella perdurable en ti. Los pensamientos profundos, el estudio de religiones poco convencionales te hacen cambiar tu modo de pensar y ver la vida. La energ\u00eda planetaria te inclina a concentrarte en tu trabajo y hasta un nuevo empleo podr\u00eda estar en agenda. N\u00fameros de suerte: 29, 13, 18.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota a los lectores: Betty B. Mercado, sobrina y colaboradora del fallecido astr\u00f3logo Walter Mercado, contin\u00faa su legado escribiendo el hor\u00f3scopo del d\u00eda. Aries (20 de marzo &#8211; 18 de abril) Estar\u00e1s ahora muy convincente y directo al comunicarte. Tu energ\u00eda se exalta y querr\u00e1s hacer mucho en poco tiempo. Esto traer\u00e1 por consecuencia diferencias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":222134,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-307265","post","type-post","status-publish","format-standard","has-post-thumbnail","category-femenina"],"acf":{"antetitulo":"Astrolog\u00eda"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hor\u00f3scopo semanal - El Diario - Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hor\u00f3scopo semanal - El Diario - Bolivia\" \/>\n<meta property=\"og:description\" content=\"Nota a los lectores: Betty B. Mercado, sobrina y colaboradora del fallecido astr\u00f3logo Walter Mercado, contin\u00faa su legado escribiendo el hor\u00f3scopo del d\u00eda. Aries (20 de marzo &#8211; 18 de abril) Estar\u00e1s ahora muy convincente y directo al comunicarte. Tu energ\u00eda se exalta y querr\u00e1s hacer mucho en poco tiempo. Esto traer\u00e1 por consecuencia diferencias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario - Bolivia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eldiario.bolivia\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T10:04:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeanette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:site\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeanette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/\"},\"author\":{\"name\":\"Jeanette\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\"},\"headline\":\"Hor\u00f3scopo semanal\",\"datePublished\":\"2025-06-04T10:04:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/\"},\"wordCount\":892,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Geminis.jpg\",\"articleSection\":[\"Femenina\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/\",\"name\":\"Hor\u00f3scopo semanal - El Diario - Bolivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Geminis.jpg\",\"datePublished\":\"2025-06-04T10:04:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Geminis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Geminis.jpg\",\"width\":1200,\"height\":675,\"caption\":\"G\u00e9minis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2025\\\/06\\\/04\\\/horoscopo-semanal-145\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hor\u00f3scopo semanal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"name\":\"El Diario - Decano de la prensa nacional\",\"description\":\"El Diario - Decano de la prensa nacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\",\"name\":\"El Diario - Decano de la prensa nacional\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"width\":272,\"height\":52,\"caption\":\"El Diario - Decano de la prensa nacional\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eldiario.bolivia\\\/\",\"https:\\\/\\\/x.com\\\/eldiario_net\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\",\"name\":\"Jeanette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"caption\":\"Jeanette\"},\"sameAs\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\"],\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/author\\\/jeanette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hor\u00f3scopo semanal - El Diario - Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/","og_locale":"es_ES","og_type":"article","og_title":"Hor\u00f3scopo semanal - El Diario - Bolivia","og_description":"Nota a los lectores: Betty B. Mercado, sobrina y colaboradora del fallecido astr\u00f3logo Walter Mercado, contin\u00faa su legado escribiendo el hor\u00f3scopo del d\u00eda. Aries (20 de marzo &#8211; 18 de abril) Estar\u00e1s ahora muy convincente y directo al comunicarte. Tu energ\u00eda se exalta y querr\u00e1s hacer mucho en poco tiempo. Esto traer\u00e1 por consecuencia diferencias [&hellip;]","og_url":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/","og_site_name":"El Diario - Bolivia","article_publisher":"https:\/\/www.facebook.com\/eldiario.bolivia\/","article_published_time":"2025-06-04T10:04:20+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg","type":"image\/jpeg"}],"author":"Jeanette","twitter_card":"summary_large_image","twitter_creator":"@eldiario_net","twitter_site":"@eldiario_net","twitter_misc":{"Escrito por":"Jeanette","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#article","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/"},"author":{"name":"Jeanette","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7"},"headline":"Hor\u00f3scopo semanal","datePublished":"2025-06-04T10:04:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/"},"wordCount":892,"publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg","articleSection":["Femenina"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/","url":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/","name":"Hor\u00f3scopo semanal - El Diario - Bolivia","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg","datePublished":"2025-06-04T10:04:20+00:00","breadcrumb":{"@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#primaryimage","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/05\/Geminis.jpg","width":1200,"height":675,"caption":"G\u00e9minis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiario.net\/portal\/2025\/06\/04\/horoscopo-semanal-145\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiario.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Hor\u00f3scopo semanal"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiario.net\/portal\/#website","url":"https:\/\/www.eldiario.net\/portal\/","name":"El Diario - Decano de la prensa nacional","description":"El Diario - Decano de la prensa nacional","publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiario.net\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiario.net\/portal\/#organization","name":"El Diario - Decano de la prensa nacional","url":"https:\/\/www.eldiario.net\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","width":272,"height":52,"caption":"El Diario - Decano de la prensa nacional"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eldiario.bolivia\/","https:\/\/x.com\/eldiario_net"]},{"@type":"Person","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7","name":"Jeanette","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","caption":"Jeanette"},"sameAs":["https:\/\/www.eldiario.net\/portal"],"url":"https:\/\/www.eldiario.net\/portal\/author\/jeanette\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/307265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/comments?post=307265"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/307265\/revisions"}],"predecessor-version":[{"id":307266,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/307265\/revisions\/307266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media\/222134"}],"wp:attachment":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media?parent=307265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/categories?post=307265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/tags?post=307265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}