{"id":224385,"date":"2024-06-02T07:08:06","date_gmt":"2024-06-02T11:08:06","guid":{"rendered":"https:\/\/www.eldiario.net\/portal\/?p=224385"},"modified":"2024-06-02T07:08:06","modified_gmt":"2024-06-02T11:08:06","slug":"habilitan-puntos-para-donar-ropa","status":"publish","type":"post","link":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/","title":{"rendered":"Habilitan puntos para donar ropa"},"content":{"rendered":"<p>El Palacio Consistorial, ubicado en la calle Mercado esquina Col\u00f3n, el edificio Feliciano Cantuta y varias subalcald\u00edas, son parte de los 13 puntos de acopio que la comuna pace\u00f1a habilit\u00f3 para que la gente done ropa abrigada y en buen estado o nueva. La campa\u00f1a denominada \u201cS\u00ed Quiero Abrigarte\u201d ser\u00e1 hasta el 21 de junio.<br \/>\nLos horarios para recibir las prendas son de 9:00 a 12:30 y de 14:30 a 18:30 horas. Los otros lugares son las subalcald\u00edas Centro, Perif\u00e9rica, Max Paredes, San Antonio, Sur, Cotahuma y Mallasa, adem\u00e1s de los hospitales municipales La Portada, los Pinos, Cotahuma y La Merced.<br \/>\nAsimismo, las farmacias Farmacorp y en la Universidad Franz Tamayo (Unifranz), tambi\u00e9n reciben los aportes.<br \/>\nLa iniciativa busca beneficiar a \u201cpersonas en situaci\u00f3n de calle, personas migrantes que vienen y tambi\u00e9n de albergues para apoyarles con el pernocte\u201d, sostuvo el secretario municipal de Educaci\u00f3n y Desarrollo Social de La Paz, Jacques Alcoba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Palacio Consistorial, ubicado en la calle Mercado esquina Col\u00f3n, el edificio Feliciano Cantuta y varias subalcald\u00edas, son parte de los 13 puntos de acopio que la comuna pace\u00f1a habilit\u00f3 para que la gente done ropa abrigada y en buen estado o nueva. La campa\u00f1a denominada \u201cS\u00ed Quiero Abrigarte\u201d ser\u00e1 hasta el 21 de junio. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":194726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-224385","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"acf":{"antetitulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Habilitan puntos para donar ropa - El Diario - Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habilitan puntos para donar ropa - El Diario - Bolivia\" \/>\n<meta property=\"og:description\" content=\"El Palacio Consistorial, ubicado en la calle Mercado esquina Col\u00f3n, el edificio Feliciano Cantuta y varias subalcald\u00edas, son parte de los 13 puntos de acopio que la comuna pace\u00f1a habilit\u00f3 para que la gente done ropa abrigada y en buen estado o nueva. La campa\u00f1a denominada \u201cS\u00ed Quiero Abrigarte\u201d ser\u00e1 hasta el 21 de junio. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario - Bolivia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eldiario.bolivia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-02T11:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeanette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:site\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeanette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/\"},\"author\":{\"name\":\"Jeanette\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\"},\"headline\":\"Habilitan puntos para donar ropa\",\"datePublished\":\"2024-06-02T11:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nacional.jpg\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/\",\"name\":\"Habilitan puntos para donar ropa - El Diario - Bolivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nacional.jpg\",\"datePublished\":\"2024-06-02T11:08:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nacional.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Nacional.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/06\\\/02\\\/habilitan-puntos-para-donar-ropa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habilitan puntos para donar ropa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"name\":\"El Diario - Decano de la prensa nacional\",\"description\":\"El Diario - Decano de la prensa nacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\",\"name\":\"El Diario - Decano de la prensa nacional\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"width\":272,\"height\":52,\"caption\":\"El Diario - Decano de la prensa nacional\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eldiario.bolivia\\\/\",\"https:\\\/\\\/x.com\\\/eldiario_net\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\",\"name\":\"Jeanette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"caption\":\"Jeanette\"},\"sameAs\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\"],\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/author\\\/jeanette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habilitan puntos para donar ropa - El Diario - Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/","og_locale":"es_ES","og_type":"article","og_title":"Habilitan puntos para donar ropa - El Diario - Bolivia","og_description":"El Palacio Consistorial, ubicado en la calle Mercado esquina Col\u00f3n, el edificio Feliciano Cantuta y varias subalcald\u00edas, son parte de los 13 puntos de acopio que la comuna pace\u00f1a habilit\u00f3 para que la gente done ropa abrigada y en buen estado o nueva. La campa\u00f1a denominada \u201cS\u00ed Quiero Abrigarte\u201d ser\u00e1 hasta el 21 de junio. [&hellip;]","og_url":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/","og_site_name":"El Diario - Bolivia","article_publisher":"https:\/\/www.facebook.com\/eldiario.bolivia\/","article_published_time":"2024-06-02T11:08:06+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg","type":"image\/jpeg"}],"author":"Jeanette","twitter_card":"summary_large_image","twitter_creator":"@eldiario_net","twitter_site":"@eldiario_net","twitter_misc":{"Escrito por":"Jeanette","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#article","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/"},"author":{"name":"Jeanette","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7"},"headline":"Habilitan puntos para donar ropa","datePublished":"2024-06-02T11:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg","articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/","url":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/","name":"Habilitan puntos para donar ropa - El Diario - Bolivia","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg","datePublished":"2024-06-02T11:08:06+00:00","breadcrumb":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#primaryimage","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/12\/Nacional.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiario.net\/portal\/2024\/06\/02\/habilitan-puntos-para-donar-ropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiario.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Habilitan puntos para donar ropa"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiario.net\/portal\/#website","url":"https:\/\/www.eldiario.net\/portal\/","name":"El Diario - Decano de la prensa nacional","description":"El Diario - Decano de la prensa nacional","publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiario.net\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiario.net\/portal\/#organization","name":"El Diario - Decano de la prensa nacional","url":"https:\/\/www.eldiario.net\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","width":272,"height":52,"caption":"El Diario - Decano de la prensa nacional"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eldiario.bolivia\/","https:\/\/x.com\/eldiario_net"]},{"@type":"Person","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7","name":"Jeanette","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","caption":"Jeanette"},"sameAs":["https:\/\/www.eldiario.net\/portal"],"url":"https:\/\/www.eldiario.net\/portal\/author\/jeanette\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/224385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/comments?post=224385"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/224385\/revisions"}],"predecessor-version":[{"id":224386,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/224385\/revisions\/224386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media\/194726"}],"wp:attachment":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media?parent=224385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/categories?post=224385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/tags?post=224385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}