{"id":203845,"date":"2024-02-18T06:38:09","date_gmt":"2024-02-18T10:38:09","guid":{"rendered":"https:\/\/www.eldiario.net\/portal\/?p=203845"},"modified":"2024-02-18T06:38:09","modified_gmt":"2024-02-18T10:38:09","slug":"dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel","status":"publish","type":"post","link":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/","title":{"rendered":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel"},"content":{"rendered":"<p>Dakota Johnson (Cincuenta sombras de Grey) encabeza el reparto de la nueva pel\u00edcula de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas e inescrutables de las publicaciones Marvel, pero no est\u00e1 sola, llega muy bien acompa\u00f1ada por algunas de las estrellas en alza del momento, como Sydney Sweeney (The White Lotus), Celeste O&#8217;Connor (Cazafantasmas: M\u00e1s all\u00e1) e Isabela Merced (Transformers: El \u00faltimo Caballero).<\/p>\n<p>La trama de la cinta gira en torno a Cassandra Webb (Dakota Johnson), una param\u00e9dica de Manhattan que, tras un aparatoso accidente, desarrolla el poder de ver el futuro&#8230; y se da cuenta de que puede utilizar esa visi\u00f3n para cambiarlo. Obligada a enfrentar revelaciones sobre su pasado, forja una relaci\u00f3n con tres mujeres j\u00f3venes destinadas a destinos poderosos&#8230; si todas pueden sobrevivir a un presente mortal.<\/p>\n<p>\u201cMadame Web se estrenar\u00e1 el jueves 15 de febrero, convirti\u00e9ndose en una de las mejores opciones para ir a ver en San Valent\u00edn\u201d, se\u00f1al\u00f3 Fabiana Cabrera, gerente de marketing de Sony Pictures \u2013 Andes Films, a\u00f1adiendo que la pel\u00edcula es el primer estreno de superh\u00e9roes del a\u00f1o y la m\u00e1s esperada del mes del amor, ofreciendo 114 minutos de acci\u00f3n, aventura y ciencia ficci\u00f3n. <\/p>\n<p>El reparto lo completan Tahar Rahim (Napole\u00f3n), Adam Scott (Separaci\u00f3n, Peque\u00f1o demonio) y Emma Roberts (American Horror Story: Delicate, Abandoned), mientras que la direcci\u00f3n est\u00e1 a cargo de la brit\u00e1nica S.J. Clarkson, quien coment\u00f3 que uno de los temas de la pel\u00edcula es que no es necesario ser sobrehumano para tener superpoderes, la mayor\u00eda de las habilidades de los superh\u00e9roes provienen de la fuerza y la agilidad, mientras que con Madame Web todo es psicol\u00f3gico.<\/p>\n<p>Le pel\u00edcula ya llego a todos los cines de Bolivia.<br \/>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #tdi_1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"tdi_1\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 2<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\" title=\"2326579 - MADAME WEB\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\" srcset=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg 1667w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-300x200.jpg 300w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-1024x682.jpg 1024w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-768x511.jpg 768w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-1536x1023.jpg 1536w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-696x463.jpg 696w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2-1068x711.jpg 1068w\" sizes=\"(max-width: 631px) 100vw, 631px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel.jpg\" title=\"2326579 - MADAME WEB\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel.jpg\" srcset=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel.jpg 1667w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-300x191.jpg 300w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-1024x651.jpg 1024w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-768x488.jpg 768w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-1536x977.jpg 1536w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-696x443.jpg 696w, https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-1068x679.jpg 1068w\" sizes=\"(max-width: 661px) 100vw, 661px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dakota Johnson (Cincuenta sombras de Grey) encabeza el reparto de la nueva pel\u00edcula de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas e inescrutables de las publicaciones Marvel, pero no est\u00e1 sola, llega muy bien acompa\u00f1ada por algunas de las estrellas en alza del momento, como Sydney Sweeney (The White Lotus), Celeste O&#8217;Connor (Cazafantasmas: M\u00e1s all\u00e1) e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":203846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-203845","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cine-mundo"],"acf":{"antetitulo":"EN CARTELERA"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia\" \/>\n<meta property=\"og:description\" content=\"Dakota Johnson (Cincuenta sombras de Grey) encabeza el reparto de la nueva pel\u00edcula de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas e inescrutables de las publicaciones Marvel, pero no est\u00e1 sola, llega muy bien acompa\u00f1ada por algunas de las estrellas en alza del momento, como Sydney Sweeney (The White Lotus), Celeste O&#8217;Connor (Cazafantasmas: M\u00e1s all\u00e1) e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/\" \/>\n<meta property=\"og:site_name\" content=\"El Diario - Bolivia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eldiario.bolivia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-18T10:38:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1667\" \/>\n\t<meta property=\"og:image:height\" content=\"1110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeanette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:site\" content=\"@eldiario_net\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeanette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/\"},\"author\":{\"name\":\"Jeanette\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\"},\"headline\":\"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel\",\"datePublished\":\"2024-02-18T10:38:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/\"},\"wordCount\":334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\",\"articleSection\":[\"Cine Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/\",\"name\":\"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\",\"datePublished\":\"2024-02-18T10:38:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg\",\"width\":1667,\"height\":1110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/2024\\\/02\\\/18\\\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"name\":\"El Diario - Decano de la prensa nacional\",\"description\":\"El Diario - Decano de la prensa nacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#organization\",\"name\":\"El Diario - Decano de la prensa nacional\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_ED.jpg\",\"width\":272,\"height\":52,\"caption\":\"El Diario - Decano de la prensa nacional\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eldiario.bolivia\\\/\",\"https:\\\/\\\/x.com\\\/eldiario_net\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/#\\\/schema\\\/person\\\/f46445640444750d7d753ccd04ae01b7\",\"name\":\"Jeanette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g\",\"caption\":\"Jeanette\"},\"sameAs\":[\"https:\\\/\\\/www.eldiario.net\\\/portal\"],\"url\":\"https:\\\/\\\/www.eldiario.net\\\/portal\\\/author\\\/jeanette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/","og_locale":"es_ES","og_type":"article","og_title":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia","og_description":"Dakota Johnson (Cincuenta sombras de Grey) encabeza el reparto de la nueva pel\u00edcula de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas e inescrutables de las publicaciones Marvel, pero no est\u00e1 sola, llega muy bien acompa\u00f1ada por algunas de las estrellas en alza del momento, como Sydney Sweeney (The White Lotus), Celeste O&#8217;Connor (Cazafantasmas: M\u00e1s all\u00e1) e [&hellip;]","og_url":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/","og_site_name":"El Diario - Bolivia","article_publisher":"https:\/\/www.facebook.com\/eldiario.bolivia\/","article_published_time":"2024-02-18T10:38:09+00:00","og_image":[{"width":1667,"height":1110,"url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg","type":"image\/jpeg"}],"author":"Jeanette","twitter_card":"summary_large_image","twitter_creator":"@eldiario_net","twitter_site":"@eldiario_net","twitter_misc":{"Escrito por":"Jeanette","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#article","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/"},"author":{"name":"Jeanette","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7"},"headline":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel","datePublished":"2024-02-18T10:38:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/"},"wordCount":334,"commentCount":0,"publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg","articleSection":["Cine Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/","url":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/","name":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel - El Diario - Bolivia","isPartOf":{"@id":"https:\/\/www.eldiario.net\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#primaryimage"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg","datePublished":"2024-02-18T10:38:09+00:00","breadcrumb":{"@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#primaryimage","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2024\/02\/Dakota-Johnson-protagoniza-Madame-Web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-Marvel-2.jpg","width":1667,"height":1110},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldiario.net\/portal\/2024\/02\/18\/dakota-johnson-protagoniza-madame-web-el-origen-de-una-de-las-heroinas-mas-enigmaticas-de-marvel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.eldiario.net\/portal\/"},{"@type":"ListItem","position":2,"name":"Dakota Johnson protagoniza \u201cMadame Web\u201d, el origen de una de las hero\u00ednas m\u00e1s enigm\u00e1ticas de Marvel"}]},{"@type":"WebSite","@id":"https:\/\/www.eldiario.net\/portal\/#website","url":"https:\/\/www.eldiario.net\/portal\/","name":"El Diario - Decano de la prensa nacional","description":"El Diario - Decano de la prensa nacional","publisher":{"@id":"https:\/\/www.eldiario.net\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eldiario.net\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eldiario.net\/portal\/#organization","name":"El Diario - Decano de la prensa nacional","url":"https:\/\/www.eldiario.net\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","contentUrl":"https:\/\/www.eldiario.net\/portal\/wp-content\/uploads\/2023\/07\/logo_ED.jpg","width":272,"height":52,"caption":"El Diario - Decano de la prensa nacional"},"image":{"@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eldiario.bolivia\/","https:\/\/x.com\/eldiario_net"]},{"@type":"Person","@id":"https:\/\/www.eldiario.net\/portal\/#\/schema\/person\/f46445640444750d7d753ccd04ae01b7","name":"Jeanette","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ea2118a5f7dad2b7138b1187a6b7ee55f160b9968b66013c3a3ef39dd7e5798?s=96&d=mm&r=g","caption":"Jeanette"},"sameAs":["https:\/\/www.eldiario.net\/portal"],"url":"https:\/\/www.eldiario.net\/portal\/author\/jeanette\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/203845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/comments?post=203845"}],"version-history":[{"count":1,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/203845\/revisions"}],"predecessor-version":[{"id":203848,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/posts\/203845\/revisions\/203848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media\/203846"}],"wp:attachment":[{"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/media?parent=203845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/categories?post=203845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldiario.net\/portal\/wp-json\/wp\/v2\/tags?post=203845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}